{"id":54,"count":4,"description":"A mostra REFRAME nasceu h\u00e1 quatro anos de uma urg\u00eancia gerada por uma safra de filmes inventivos e inclassific\u00e1veis; essa tend\u00eancia cresceu e se ramificou nas mais variadas experi\u00eancias est\u00e9ticas e narrativas. O cruzamento entre o melodrama e o horror queer; as experi\u00eancias individuais e sensoriais do corpo e do g\u00eanero levadas a extremos anal\u00f3gicos e tecnol\u00f3gicos; os territ\u00f3rios da dan\u00e7a, da literatura, da performance costurando o audiovisual com agulha e linha genderfluid. Tudo se mistura e se harmoniza.","link":"https:\/\/rede.mixbrasil.org.br\/32\/categoria\/reframe-pt\/longas-pt\/","name":"REFRAME LONGAS","slug":"longas-pt","taxonomy":"category","parent":1257,"meta":[],"_links":{"self":[{"href":"https:\/\/rede.mixbrasil.org.br\/32\/wp-json\/wp\/v2\/categories\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rede.mixbrasil.org.br\/32\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/rede.mixbrasil.org.br\/32\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/rede.mixbrasil.org.br\/32\/wp-json\/wp\/v2\/categories\/1257"}],"wp:post_type":[{"href":"https:\/\/rede.mixbrasil.org.br\/32\/wp-json\/wp\/v2\/posts?categories=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}